{"id":1762,"date":"2024-11-19T15:02:34","date_gmt":"2024-11-19T14:02:34","guid":{"rendered":"https:\/\/www.dolomitenmedicalclinic.it\/medici\/dott-bianco-mario\/"},"modified":"2026-01-14T10:39:49","modified_gmt":"2026-01-14T09:39:49","slug":"dr-bianco-mario","status":"publish","type":"medici","link":"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/","title":{"rendered":"Dr. Mario Bianco"},"content":{"rendered":"<p>Eye surgeon<\/p>\n","protected":false},"featured_media":1763,"parent":0,"template":"","class_list":["post-1762","medici","type-medici","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr. Mario Bianco - Dolomiten Medical Clinic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Mario Bianco - Dolomiten Medical Clinic\" \/>\n<meta property=\"og:description\" content=\"Eye surgeon\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/\" \/>\n<meta property=\"og:site_name\" content=\"Dolomiten Medical Clinic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RuffinellaClinics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T09:39:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dolomitenmedicalclinic.it\/wp-content\/uploads\/2024\/11\/MARIO-BIANCO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/en\\\/medici\\\/dr-bianco-mario\\\/\",\"url\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/en\\\/medici\\\/dr-bianco-mario\\\/\",\"name\":\"Dr. Mario Bianco - Dolomiten Medical Clinic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/en\\\/medici\\\/dr-bianco-mario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/en\\\/medici\\\/dr-bianco-mario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MARIO-BIANCO-e1774611085651.jpg\",\"datePublished\":\"2024-11-19T14:02:34+00:00\",\"dateModified\":\"2026-01-14T09:39:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/en\\\/medici\\\/dr-bianco-mario\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/en\\\/medici\\\/dr-bianco-mario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/en\\\/medici\\\/dr-bianco-mario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MARIO-BIANCO-e1774611085651.jpg\",\"contentUrl\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MARIO-BIANCO-e1774611085651.jpg\",\"width\":960,\"height\":960,\"caption\":\"Dolomiten Medical Clinic - Ambulatori privati Trentino Alto Adige\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/en\\\/medici\\\/dr-bianco-mario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medici\",\"item\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/medici\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dr. Mario Bianco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/#website\",\"url\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/\",\"name\":\"Dolomiten Medical Clinic\",\"description\":\"Dolomiten Medical Clinic\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/#organization\",\"name\":\"Dolomiten Medical Clinic\",\"url\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Risorsa-3.svg\",\"contentUrl\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Risorsa-3.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Dolomiten Medical Clinic\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dolomitenmedicalclinic.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RuffinellaClinics\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Mario Bianco - Dolomiten Medical Clinic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/","og_locale":"en_US","og_type":"article","og_title":"Dr. Mario Bianco - Dolomiten Medical Clinic","og_description":"Eye surgeon","og_url":"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/","og_site_name":"Dolomiten Medical Clinic","article_publisher":"https:\/\/www.facebook.com\/RuffinellaClinics","article_modified_time":"2026-01-14T09:39:49+00:00","og_image":[{"width":960,"height":960,"url":"https:\/\/www.dolomitenmedicalclinic.it\/wp-content\/uploads\/2024\/11\/MARIO-BIANCO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/","url":"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/","name":"Dr. Mario Bianco - Dolomiten Medical Clinic","isPartOf":{"@id":"https:\/\/www.dolomitenmedicalclinic.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/#primaryimage"},"image":{"@id":"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dolomitenmedicalclinic.it\/wp-content\/uploads\/2024\/11\/MARIO-BIANCO-e1774611085651.jpg","datePublished":"2024-11-19T14:02:34+00:00","dateModified":"2026-01-14T09:39:49+00:00","breadcrumb":{"@id":"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/#primaryimage","url":"https:\/\/www.dolomitenmedicalclinic.it\/wp-content\/uploads\/2024\/11\/MARIO-BIANCO-e1774611085651.jpg","contentUrl":"https:\/\/www.dolomitenmedicalclinic.it\/wp-content\/uploads\/2024\/11\/MARIO-BIANCO-e1774611085651.jpg","width":960,"height":960,"caption":"Dolomiten Medical Clinic - Ambulatori privati Trentino Alto Adige"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dolomitenmedicalclinic.it\/en\/medici\/dr-bianco-mario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dolomitenmedicalclinic.it\/en\/"},{"@type":"ListItem","position":2,"name":"Medici","item":"https:\/\/www.dolomitenmedicalclinic.it\/medici\/"},{"@type":"ListItem","position":3,"name":"Dr. Mario Bianco"}]},{"@type":"WebSite","@id":"https:\/\/www.dolomitenmedicalclinic.it\/#website","url":"https:\/\/www.dolomitenmedicalclinic.it\/","name":"Dolomiten Medical Clinic","description":"Dolomiten Medical Clinic","publisher":{"@id":"https:\/\/www.dolomitenmedicalclinic.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dolomitenmedicalclinic.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dolomitenmedicalclinic.it\/#organization","name":"Dolomiten Medical Clinic","url":"https:\/\/www.dolomitenmedicalclinic.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dolomitenmedicalclinic.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.dolomitenmedicalclinic.it\/wp-content\/uploads\/2024\/09\/Risorsa-3.svg","contentUrl":"https:\/\/www.dolomitenmedicalclinic.it\/wp-content\/uploads\/2024\/09\/Risorsa-3.svg","width":"1024","height":"1024","caption":"Dolomiten Medical Clinic"},"image":{"@id":"https:\/\/www.dolomitenmedicalclinic.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RuffinellaClinics"]}]}},"_links":{"self":[{"href":"https:\/\/www.dolomitenmedicalclinic.it\/en\/wp-json\/wp\/v2\/medici\/1762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dolomitenmedicalclinic.it\/en\/wp-json\/wp\/v2\/medici"}],"about":[{"href":"https:\/\/www.dolomitenmedicalclinic.it\/en\/wp-json\/wp\/v2\/types\/medici"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dolomitenmedicalclinic.it\/en\/wp-json\/wp\/v2\/media\/1763"}],"wp:attachment":[{"href":"https:\/\/www.dolomitenmedicalclinic.it\/en\/wp-json\/wp\/v2\/media?parent=1762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}